{"id":900,"date":"2019-07-26T12:53:13","date_gmt":"2019-07-26T12:53:13","guid":{"rendered":"https:\/\/www.kaffeeform.com\/?p=900"},"modified":"2019-12-09T16:05:00","modified_gmt":"2019-12-09T15:05:00","slug":"victoria-albert-museum-london","status":"publish","type":"post","link":"https:\/\/www.kaffeeform.com\/de\/victoria-albert-museum-london\/","title":{"rendered":"FOOD. Bigger than the Plate"},"content":{"rendered":"\n<p>Kaffeeform ist Teil der zukunftsweisenden Ausstellung, die noch bis zum 20. Oktober im Victoria &amp; Albert Museum in London zu sehen ist.   <\/p>\n\n\n\n<p>In unserem Zeitalter von massiven \u00f6kologischen Herausforderungen, sich rasant ver\u00e4ndernden Gesellschaften und technischen Innovationen ist die Beziehung zwischen Mensch und Lebensmitteln zunehmend Teil der \u00f6ffentlichen Debatte. Ern\u00e4hrung kann ein machtvolles Instrument sein um die Welt in der wir Leben zu gestalten.<\/p>\n\n\n\n<p>Die umfangreiche Ausstellung will erkunden wie innovative Personen, Gemeinschaften und Organisationen auf radikale Art und Weise neu erfinden wie Lebensmittel angebaut, verteilt und erlebt werden. Besucher begeben sich auf eine sensorische Reise durch den Lebensmittelkreislauf; auf \u00fcberraschende und spielerische Weise werden dabei Fragen aufgeworfen, wie wir durch gemeinsame Entscheidungen auch in Zukunft nachhaltig, fair und lecker essen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p>FOOD &#8211; Bigger than the Plate zeigt \u00fcber 70 zeitgem\u00e4\u00dfe Projekte die in Zusammenarbeit zwischen K\u00fcnstlern und Designern mit K\u00f6chen, Bauern, Wissenschaftlern und lokalen Gruppen entstanden sind. Unterteilt in vier Sektionen \u2013 Kompost, Landwirtschaft, Handel und Essen \u2013 sind unsere Kaffeeform Produkte in der Sektion \u201cKompost\u201d zu sehen und dar\u00fcber hinaus im Museumsshop des V&amp;A Museums erh\u00e4ltlich.<br>Der Besuch der Ausstellung ist sehr zu empfehlen. Mehr \u00fcber die Kaffeeform Produkte und Entstehung<a href=\"https:\/\/www.kaffeeform.com\/story\"> ist hier zu lesen.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kaffeeform ist Teil der zukunftsweisenden Ausstellung, die noch bis zum 20. Oktober im Victoria &amp; Albert Museum in London zu sehen ist. In unserem Zeitalter von massiven \u00f6kologischen Herausforderungen, sich rasant ver\u00e4ndernden Gesellschaften und technischen Innovationen ist die Beziehung zwischen Mensch und Lebensmitteln zunehmend Teil der \u00f6ffentlichen Debatte. Ern\u00e4hrung kann ein machtvolles Instrument sein um&#8230;<\/p>\n","protected":false},"author":5,"featured_media":901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[65],"tags":[60,61,59,50,63],"class_list":["post-900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotted","tag-ausstellung","tag-design","tag-exhibition","tag-kaffeeform","tag-london"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts\/900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/media\/901"}],"wp:attachment":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/categories?post=900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/tags?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}