{"id":942,"date":"2019-07-29T16:13:08","date_gmt":"2019-07-29T16:13:08","guid":{"rendered":"https:\/\/www.kaffeeform.com\/?p=942"},"modified":"2019-12-09T16:04:30","modified_gmt":"2019-12-09T15:04:30","slug":"earth-overshoot-day","status":"publish","type":"post","link":"https:\/\/www.kaffeeform.com\/de\/earth-overshoot-day\/","title":{"rendered":"Earth Overshoot Day"},"content":{"rendered":"\n<p>Ab dem 29. Juli 2019 sind die j\u00e4hrlichen nat\u00fcrlichen Ressourcen der Erde ersch\u00f6pft, wir leben \u00f6kologisch auf Pump. Denken wir an eine Speisekammer, gef\u00fcllt um die gesamte Menschheit ein Jahr zu ern\u00e4hren, w\u00e4ren alle Vorr\u00e4te bereits jetzt aufgegessen, die Kammer leer. Ein Desaster.<\/p>\n\n\n\n<p>Im Vergleich zum letzten Jahr ist der globale Erd\u00fcberlastungstag um drei Tage nach vorne ger\u00fcckt, das hei\u00dft, die \u00dcberlastung nimmer weiter zu. Unserem \u00d6kosystem wurden mehr Holz, Fisch, Nahrungsmittel, Pflanzen oder Futtermittel entnommen, als im Laufe des Jahres nachwachsen oder wieder wieder generiert werden kann. Wir sto\u00dfen mehr Treibhausgase in die Atmosph\u00e4re aus, als von nat\u00fcrlichen Kreisl\u00e4ufen wieder aufgenommen wird. Ab heute zerst\u00f6ren Menschen also theoretisch die Grundlagen f\u00fcr nachfolgende Generationen, ihre Speisekammern anlegen zu k\u00f6nnen.<\/p>\n\n\n\n<p>Rein rechnerisch verbraucht die gesamte Weltbev\u00f6lkerung ganze 1,75 Erden. Deutschland hat seine nat\u00fcrlich verf\u00fcgbaren Ressourcen f\u00fcr 2019 bereits am 3. Mai aufgebraucht. Besonders bitter in diesem Zusammenhang ist der verschwenderische Umgang mit Ressourcen wie B\u00f6den, Wasser, und Lebensmitteln: nach Angaben des Umweltbundesamts landet davon in Deutschland ca. ein Drittel im M\u00fcll.&nbsp;<\/p>\n\n\n\n<p>Das wollen wir \u00e4ndern! Kaffeeform fordert einen neuen, bewussteren Blick auf Ressourcen: Wir m\u00fcssen das, was wir haben, schonen. Nachhaltiger, und in Kreisl\u00e4ufen denken. Konsum- und Kaufentscheidungen bewusst treffen, unseren Lebensstil \u00e4ndern. <\/p>\n\n\n\n<p><em><a href=\"http:\/\/kaffeeform.com\/about\">Mehr \u00fcber die Mission von Kaffeeform erfahren.<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ab dem 29. Juli 2019 sind die j\u00e4hrlichen nat\u00fcrlichen Ressourcen der Erde ersch\u00f6pft, wir leben \u00f6kologisch auf Pump. Denken wir an eine Speisekammer, gef\u00fcllt um die gesamte Menschheit ein Jahr zu ern\u00e4hren, w\u00e4ren alle Vorr\u00e4te bereits jetzt aufgegessen, die Kammer leer. Ein Desaster. Im Vergleich zum letzten Jahr ist der globale Erd\u00fcberlastungstag um drei Tage&#8230;<\/p>\n","protected":false},"author":5,"featured_media":922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66],"tags":[71,68,69,70,50,74,52,73],"class_list":["post-942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saveourplanet","tag-movetheday","tag-earthovershootday","tag-earthovershootday2019","tag-eod2019","tag-kaffeeform","tag-ressourcenschonung","tag-sustainability","tag-sustainabledesign"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts\/942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/comments?post=942"}],"version-history":[{"count":0,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/posts\/942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/media\/922"}],"wp:attachment":[{"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/media?parent=942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/categories?post=942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaffeeform.com\/de\/wp-json\/wp\/v2\/tags?post=942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}